{"id":1157,"date":"2018-10-01T10:16:11","date_gmt":"2018-10-01T08:16:11","guid":{"rendered":"https:\/\/ninalaguerrera.org\/?p=1157"},"modified":"2018-10-01T10:16:11","modified_gmt":"2018-10-01T08:16:11","slug":"guerrier-in-azione-i-tifosi-di-nina","status":"publish","type":"post","link":"https:\/\/ninalaguerrera.org\/it\/2018\/10\/01\/guerrier-in-azione-i-tifosi-di-nina\/","title":{"rendered":"Guerrier@ In Azione: I tifosi di Nina"},"content":{"rendered":"<p>Ciao Guerrier@!<\/p>\n<p>Come sapete, i miei due paesi &#8211; Italia e Spagna &#8211; hanno molte cose in comune ed essendo una di esse l&#8217;inclinazione per il calcio, oggi voglio parlarvi di Guerrer@ in Azione molto speciali: i miei tifosi italiani, i guerrer@ tifosi!<\/p>\n<p>Io non so ancora se la Glicogenosi mi permetter\u00e0 di giocare a calcio nella mia vita; infatti, richiede molta energia, e dunque glucosio, e dato che il mio corpo non lo produce e\u00b4 difficile per me poter praticare sport intensi. Inoltre, essendo un sport di contatto, se mi dessero un colpo al fegato o alla milza che ho ingrossati, potrei correre rischi seri. Credo mi toccher\u00e0 pensare a sport meno intensi, ma vedremo.. in queste ultime settimane il mio sport principale sono stati i 10 metri di gattoneo nel materassino ed ora ho cominciando anche ad afferrarmi alla sbarra della culla, del box e viaaaaa, hop hop, sotto, su`, giu`&#8230;. un, due, un, sono in s\u00faper forma!<\/p>\n<p>A proposito di essere e mettersi in forma: vi state allenando per la I Corsa e Trekking solidale di Nina la Guerriera? Spero che s\u00ec! Appuntatevi se potete, se sarete in Andalucia il 7 di ottobre! Sara\u00b4una giornata geniale, da ricordare, che unira\u00b4 sport, solidariet\u00e0, salute, ricerca, medio-ambiente, convivenza e ci saranno regali-sorpresa! Non ve lo perdete, si sono gia\u00b4 iscritte pi\u00f9 di 500 persone! Che super festa monteremo! J<\/p>\n<p>Ritornando al tema dello sport e la glicogenosi, vi racconto che, qualsiasi cosa decida di fare, sar\u00e0 fondamentale che possa imparare a tollerare ed assumere l\u00e1mido di mais. Come vi spiegai anche nella web, l\u00e1mido di mais crudo (maizena) pu\u00f2 aiutarmi a mantenere livelli di glucosio pi\u00f9 stabili per sopravvivere e per tempi piu\u00b4 lunghi della ora di adesso.. (si\u00b4, ve l\u00b4avevo detto che da giugno i miei biberoin o papette solo mi fanno durare con glicemia stabile per una ora? Poi devo mangiare di nuovo, al 90% tutto per sonda naso-gastrica.. eh si, perche\u00b4 io la fame non la sento proprio!) All&#8217;essere un carboidrao che si assorbe lentamente attraverso l\u00b4apparato digestivo, il glucosio del cibo che assumo si va introducendo e mantenendo nel sangue per tempo piu\u00b4lungo e cos\u00ec non vado tanto facilmente in ipoglicemia.<\/p>\n<p>In realt\u00e0, e\u00b4 da varie settimane che sono in ospedale cercando di introdurre la maizena nella mia dieta ma ancora non ho ottenuto i risultati sperati.. \u00c8 un processo difficile dato che la maizena bisogna prenderla cruda, io sono ancora molto piccola ed il mio stomaco ed intestino sono sensibili, quindi figuratevi, si introduce un grammo a settimana e si vede se il corpo la tollera.. se si si continua. Poi perche\u00b4funzioni bisogna vedere se il corpo la assimila.. devo arrivare a ciurc 15 grammi ogni poche ore (2.5 forse 3) insomma, il cammino e\u00b4 lungo mamma e papa\u00b4mi accompagnano sempre!<\/p>\n<p>Qualche mese fa avevo provato ma mi ero baccata due infezioni con ricoveri ospedalieri, flebo, e tutto il dramma di cui vi avevo accennato precedentemente, per cui il tutto si era fermato.. Questa volta andiamo pian pianino e speriamo di avere fortuna! Di fatto mangiando ogni ora, non riesco a fare molte attivita\u00b4.. in pratica quando mamma ha pulito la sonda, e\u00b4gia\u00b4ora di ricominciare! Per ora vedo che ci sono giorni migliori e giorni peggiori e se il mio intestino si stanca e si infiamma vado in ipoglicemia rapido e le pause tra cibi devono essere ancora pi\u00f9 brevi. Alcune notti fa mi si e\u00b4 abbassata la glicemia a poco piu\u00b4di 20 (il minimo deve essere 70, vi ricordate?), mi hanno trovata fredda e senza quasi respiro.. che paura! Mi diedero un bolus di siero di glucosa attraverso la sonda naso-gastrica e dopo 20 minuti ero tornata in me.<\/p>\n<p>Io ho tanti angeli custodi, oltre ai miei dottori, uno di loro e\u00b4 Magaly detta da noi la &#8220;profe&#8221;: e\u00b4 la mamma di una ragazza che ha anche lei glucogenosis 1b. Lei e\u00b4saggia, ha imparato molto in questi anni in cui si e\u00b4preso cura di sua figlia e ha conosciuto il dottor Weinstein e ci ha aiutato un sacco con consigli e spronandoci a indagare le cause della mia instabilita\u00b4. Un giorno ci disse anche che sua figlia ha la glicemia pi\u00f9 stabile quando \u00e8 contenta e ride molto mentre se le abbassa quando e\u00b4stressata, quindi siccome io rido un sacco, spero di migliorare nei prossimi mesi! \ud83d\ude42<\/p>\n<p>Bene, capite gi\u00e0 che io e il mio deficit di attenzione andiamo nella stessa linea, saltando di un tema ad un altro! Papa\u00b4dice sempre che io sono come la mia mamma: ha sempre mille idee in testa e fa mille cose contemporaneamente, e\u00b4\u201dmulti-tasking\u201d \u00b4ed efficiente ma spesso si perde in mille fanstasie&#8230; Va beh, andiamo al sodo!<\/p>\n<p>Volevo parlarvi dei guerrer@s tifosi e raccontarvi che grazie ad un articolo della stampa italiana regionale sulla mia malattia in cui i miei nonni raccontavano di me, gli Ultra\u00b4 della squadra di calcio di serie B del Venezia, la &#8220;Curva Sud Venezia Mestre 1987\u201d si sono trasformati in <em>Guerrieri In Azione<\/em> e si uniti alla nostra causa incoragginado giocatori e societa\u00b4ad aderire e raccogliere fondi per la GSD 1B! <em>Fioi, che bea cosa che ga ve fato! (veneziano)<\/em><\/p>\n<p>Alla partita Venezia &#8211; Benevento che si gioc\u00f2 il passato venerd\u00ec 14 di settembre alle 21:00 a Venezia, i tifosi ondeggiavano una delle mie bandiere allo stadio. Inoltre, stabilirono un punto di raccolta fondi, annunciarono la causa per megafono, fecero un volantino con la mia bandiera, etc&#8230;<\/p>\n<p><a href=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/09\/IMG_3693.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1149 aligncenter\" src=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/09\/IMG_3693.png\" alt=\"\" width=\"359\" height=\"202\" srcset=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/09\/IMG_3693.png 359w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/09\/IMG_3693-300x169.png 300w\" sizes=\"auto, (max-width: 359px) 100vw, 359px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/09\/IMG_3694.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1150 aligncenter\" src=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/09\/IMG_3694.png\" alt=\"\" width=\"359\" height=\"271\" srcset=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/09\/IMG_3694.png 359w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/09\/IMG_3694-300x226.png 300w\" sizes=\"auto, (max-width: 359px) 100vw, 359px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>E\u00a0la cosa migliore di tutte, perfino la squadra rivale si un\u00ec in solidariet\u00e0 e fece un volantino con il logo della squadra e il motto &#8220;Nina, Non Mollare&#8221;!<\/p>\n<p><a href=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/09\/3115f828-d5de-47ad-93eb-a2901035078b.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1148 aligncenter\" src=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/09\/3115f828-d5de-47ad-93eb-a2901035078b.jpg\" alt=\"\" width=\"294\" height=\"281\" \/><\/a><\/p>\n<p>Il comitato organizzatore degli Ultra\u00b4 del Venezia-Mestre hanno anche cercato di di fare eco all\u00edniziativa con altre squadre e in altre sedi in centro-Italia Io, che ho il cuore mezzo veneto e mezzo spagnolo ne vado proprio fiera! <em>I se el mejo!<\/em> (veneziano). Grazie Andrea, Elena, Mattia, Francesca e tutti gli altri per me anonimi ma di gran cuore che hanno lanciato l`niziativa! Grazie Benevento! Tra l\u00b4altro la mamma ha conosciuto qualcuno delgi ultra del venezia-Mestre anche se in via virtuale e sono proprio stupendi! Ho gia\u00b4un futuro amico nuovo che si chiama Mattia, ha 5 anni, e spero di conoscerlo di persona presto J <em>i te ciapo per man (veneziano)!<\/em><\/p>\n<p>Proprio bello che le rivalita\u00b4vadano oltre per una causa benefica comune i <em>che beo che se sentirme Venessiana,<\/em> <em>me ven le lagreme ai oci!<\/em> (veneziano). Quando potremmo tornare in Italia andremo tutti e 3 a conoscere glu Ultra\u00b4 per abbracciarli tutti!<\/p>\n<p>Gli esseri umani tra loro hanno molte cose in comune, quelle che ci uniscono sono in numero maggiore di quelle che ci separano. Concentramoci nelle prime che le cose buone si contagiano \u2013 <em>Venessia, te coro drio!<\/em> \ud83d\ude09<\/p>\n<p>Un forte NinAbbraccio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ciao Guerrier@! Come sapete, i miei due paesi &#8211; Italia e Spagna &#8211; hanno molte cose in comune ed essendo una di esse l&#8217;inclinazione per il calcio, oggi voglio parlarvi di Guerrer@ in Azione molto speciali: i miei tifosi italiani, i guerrer@ tifosi! Io non so ancora se la Glicogenosi mi permetter\u00e0 di giocare a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1163,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[5],"tags":[],"class_list":["post-1157","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-categorizzato"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/09\/IMG_8293.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pa1s8Y-iF","_links":{"self":[{"href":"https:\/\/ninalaguerrera.org\/it\/wp-json\/wp\/v2\/posts\/1157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ninalaguerrera.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ninalaguerrera.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ninalaguerrera.org\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ninalaguerrera.org\/it\/wp-json\/wp\/v2\/comments?post=1157"}],"version-history":[{"count":2,"href":"https:\/\/ninalaguerrera.org\/it\/wp-json\/wp\/v2\/posts\/1157\/revisions"}],"predecessor-version":[{"id":1162,"href":"https:\/\/ninalaguerrera.org\/it\/wp-json\/wp\/v2\/posts\/1157\/revisions\/1162"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ninalaguerrera.org\/it\/wp-json\/wp\/v2\/media\/1163"}],"wp:attachment":[{"href":"https:\/\/ninalaguerrera.org\/it\/wp-json\/wp\/v2\/media?parent=1157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ninalaguerrera.org\/it\/wp-json\/wp\/v2\/categories?post=1157"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ninalaguerrera.org\/it\/wp-json\/wp\/v2\/tags?post=1157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}