{"id":1231,"date":"2018-10-19T14:04:41","date_gmt":"2018-10-19T12:04:41","guid":{"rendered":"https:\/\/ninalaguerrera.org\/?p=1231"},"modified":"2018-10-19T16:09:05","modified_gmt":"2018-10-19T14:09:05","slug":"trilogia-dun-compleanno-episodio-i-la-bataglia-de-los-alamos","status":"publish","type":"post","link":"https:\/\/ninalaguerrera.org\/it\/2018\/10\/19\/trilogia-dun-compleanno-episodio-i-la-bataglia-de-los-alamos\/","title":{"rendered":"Trilogia d&#8217;un compleanno &#8211; Episodio I: la battaglia &#8220;de los \u00c1lamos&#8221;"},"content":{"rendered":"<p>Ciao Guerrier@!<\/p>\n<p>Che primo compleanno con i fiocchi ho trascorso, ho festeggiato una settimana intera! La glicogenosis ci limita pero non ci ferma!<\/p>\n<p>Iniziamo dal 7 di octubre de 2018, una data che passera\u00b4 alla storia come la giornata in cui Nina e i suoi Guerrier@ hanno vinto la I battaglia a favore delle ricerca sulla glicogenosis tipo 1b.<\/p>\n<p>Sapete gia\u00b4che sono una chiaccherona e che mi piace raccontarvi tutte le cose che sto vivendo. Inoltre, \u00faltimamente sto apprendendo qualche parola: da quando ho imparato a dire Ciao in spagnolo ovvero \u201cHola\u201d, credo che lo ripeto piu\u00b4di 50 volte al giorno accompagnandolo da un movimiento di mano e braccio tipico di una lider&#8230; cosi\u00b4come nella foto piu\u00b4sotto hehehe<\/p>\n<p><a href=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/Ninasaluda.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1192 aligncenter\" src=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/Ninasaluda-1024x683.jpg\" alt=\"\" width=\"271\" height=\"181\" srcset=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/Ninasaluda-1024x683.jpg 1024w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/Ninasaluda-300x200.jpg 300w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/Ninasaluda-768x512.jpg 768w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/Ninasaluda-1500x1000.jpg 1500w\" sizes=\"auto, (max-width: 271px) 100vw, 271px\" \/><\/a><\/p>\n<p>Dico \u201cHola\u201d a Dottori, infermieri, fisio, ausiliari, terapeuta, personale delle pulizie, a tutti quelli che entrano e salgono della stanza dell\u00b4ospedale (da cui sicuramente l\u00b4ho appreso!), dico \u201chola\u201d sempre quando si aprono gli ascensori, anche se non c\u00e9\u00b4 nessuno dentro&#8230; giusto in caso\u2026 dico \u201cHola\u201d y \u201cUau\u201d ai cani, incluso dico \u201cHola\u201d agli alberi, al mare, all\u00b4alba e a tutto cio\u00b4 che ho di fronte. Tutto questo perche\u00b4 oltre ad essere una guerriera, sono molto educata. Dico anche \u201cGracias\u201d e \u201cAdios\u201d e i miei genitori fanno tutto il possibile affinche\u00b4 possa dire anche \u201cCiao\u201d dato che sono mezza italiana (ma per ora il bombardamento sonoro e\u00b4 per lo piu\u00b4 in spagnolo..)!<\/p>\n<p>Vabbeh, dicevo.. Nonostante sia abastanza chiaccherona \u00faltimamente, oggi mi mancano le parole. Piu\u00b4penso a come raccontarvi quanto speciale sia stato il festeggiamento anticipato del mio compleanno con la prima corsa e trekking solidale Nina la Guerriera (evento celebrato in Spagna: <a href=\"https:\/\/ninalaguerrera.org\/i-carrera-y-senderismo-solidarios-nina-la-guerrera\/\">I Carrera y senderismo solidarios Nina la Guerrera<\/a><u>)<\/u>, quello che ha significato per me, i miei genitori e quanti sia grata.. \u201cGrazie infinite\u201d, e\u00b4 dire poco.<\/p>\n<p>Forse potrei inizare con il raccontarvi cosa mi hanno regalato: <strong>Amore, Affetto, Solidarieta\u00b4, Speranza, Empat\u00eda, Buoni Sentimenti, Sport, Divertimento, Natura e Ricerca\u2026<\/strong> Piu\u00b4 di mille persone appoggiando la mia causa camminando, correndo o attraverso l\u00b4appoggio via acquisizione della \u201cPettorina 0 o solidale\u201d. Solo con 1 anno di vita e gia\u00b4 mi hanno regalatotutto questo, non potevo chiedere di piu\u00b4per il mio compleanno!<\/p>\n<p><a href=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/carrera-todos-juntos.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1193 aligncenter\" src=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/carrera-todos-juntos.jpg\" alt=\"\" width=\"960\" height=\"640\" srcset=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/carrera-todos-juntos.jpg 960w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/carrera-todos-juntos-300x200.jpg 300w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/carrera-todos-juntos-768x512.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Il 7 di ottobre e\u00b4stato un giorno speciale in molti sensi e mi piacerebbe illustrarlo descrivendo un paio di momenti speciali. Innanzitutto avevo ottenuto un permesso speciale di uscita dall\u00b4ospedale per diversi giorni, yuhuuu!! Mi ero svegliata come tutte le mattine, ogni due ore, misurandomi la la glicemia e cambiando il siero di glucosa che ricevo a flusso continuo la notte per sonda naso-gastrica, per il latte di soia con cereali senza glutine e amido di mais con cui inizio la giornata. Dopo la prima pausa, siccome faceva bel tempo, la mia mamma e la mia nonna Lola mi avevano dato il secondo biberon nella terrazza al sole, da cui si vede il parco dove si inaugurava l\u00b4evento.. mi piace la sensazione del sole sulla faccia la mattina quando ancora non e\u00b4 forte e posso prenderlo anch\u00b4io senza bruciare troppo velocemente glucosio, quando sembra che la stessa natura mi stia accarezzando.. Dalla terrazza che sta di fronte alla via Alamos, potevo ascoltare i guerrier@ e la loro m\u00fasica.. sapevo che era iniziata la battaglia e gia\u00b4 ero molto orgogliosa di loro.<\/p>\n<p>Alle 9:00, al \u201cfronte\u201d, i guerrier@ camminatori uscivano decisi a godersi il trekking..<\/p>\n<p><a href=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/MG_8361_1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1209\" src=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/MG_8361_1-1024x683.jpg\" alt=\"\" width=\"455\" height=\"304\" srcset=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/MG_8361_1-1024x683.jpg 1024w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/MG_8361_1-300x200.jpg 300w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/MG_8361_1-768x512.jpg 768w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/MG_8361_1-1500x1000.jpg 1500w\" sizes=\"auto, (max-width: 455px) 100vw, 455px\" \/><\/a> <a href=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/MG_8378_1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1210\" src=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/MG_8378_1-1024x683.jpg\" alt=\"\" width=\"468\" height=\"312\" srcset=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/MG_8378_1-1024x683.jpg 1024w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/MG_8378_1-300x200.jpg 300w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/MG_8378_1-768x512.jpg 768w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/MG_8378_1-1500x1000.jpg 1500w\" sizes=\"auto, (max-width: 468px) 100vw, 468px\" \/><\/a><a href=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/senderismo-y-mota.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1213\" src=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/senderismo-y-mota-768x1024.jpg\" alt=\"\" width=\"230\" height=\"307\" srcset=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/senderismo-y-mota-768x1024.jpg 768w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/senderismo-y-mota-225x300.jpg 225w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/senderismo-y-mota.jpg 1200w\" sizes=\"auto, (max-width: 230px) 100vw, 230px\" \/><\/a><\/p>\n<p>Poi, alle 10:00 uscivano altri guerrier@ che avevano deciso di affontare la battaglia correndo\u2026<\/p>\n<p><a href=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0039.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1194\" src=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0039-1024x683.jpg\" alt=\"\" width=\"385\" height=\"257\" srcset=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0039-1024x683.jpg 1024w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0039-300x200.jpg 300w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0039-768x512.jpg 768w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0039-1500x1000.jpg 1500w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0039.jpg 1732w\" sizes=\"auto, (max-width: 385px) 100vw, 385px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0048.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1199\" src=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0048-1024x683.jpg\" alt=\"\" width=\"414\" height=\"276\" srcset=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0048-1024x683.jpg 1024w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0048-300x200.jpg 300w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0048-768x512.jpg 768w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0048-1500x1000.jpg 1500w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0048.jpg 1732w\" sizes=\"auto, (max-width: 414px) 100vw, 414px\" \/><\/a> <a href=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/corredoras-y-mota.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1212\" src=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/corredoras-y-mota-683x1024.jpg\" alt=\"\" width=\"216\" height=\"324\" srcset=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/corredoras-y-mota-683x1024.jpg 683w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/corredoras-y-mota-200x300.jpg 200w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/corredoras-y-mota-768x1152.jpg 768w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/corredoras-y-mota-1500x2250.jpg 1500w\" sizes=\"auto, (max-width: 216px) 100vw, 216px\" \/><\/a><a href=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0061.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1198 alignleft\" src=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0061-1024x683.jpg\" alt=\"\" width=\"409\" height=\"273\" srcset=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0061-1024x683.jpg 1024w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0061-300x200.jpg 300w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0061-768x512.jpg 768w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0061-1500x1000.jpg 1500w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0061.jpg 1732w\" sizes=\"auto, (max-width: 409px) 100vw, 409px\" \/><\/a><\/p>\n<p>Mi ha molto emozionata vederli arrivare fino alla mia via, la <em>calle \u00c1lamos<\/em>, avendo la fortuna di poterli salutare in persona dalla terrazza\u2026 con uno di questi \u201cNina-Holas\u201d che ho menzionato prima.<\/p>\n<p><a href=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0085.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1197 aligncenter\" src=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0085-1024x683.jpg\" alt=\"\" width=\"430\" height=\"287\" srcset=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0085-1024x683.jpg 1024w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0085-300x200.jpg 300w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0085-768x512.jpg 768w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0085-1500x1000.jpg 1500w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0085.jpg 1732w\" sizes=\"auto, (max-width: 430px) 100vw, 430px\" \/><\/a><\/p>\n<p>Loro ricambiavano il saluto da li\u00b4 sotto, mentre giusto di fronte, all\u00b4orizzonte, in quello che chiamano \u201clos Tajos\u201d, potevo vedere la silouette dei guerrier@ che avevano deciso di camminare e che ho salutato anche se da lontano.<\/p>\n<p><a href=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/senderistas-frontline.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1203 aligncenter\" src=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/senderistas-frontline-1024x683.jpg\" alt=\"\" width=\"428\" height=\"286\" srcset=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/senderistas-frontline-1024x683.jpg 1024w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/senderistas-frontline-300x200.jpg 300w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/senderistas-frontline-768x512.jpg 768w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/senderistas-frontline-1500x1000.jpg 1500w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/senderistas-frontline.jpg 1732w\" sizes=\"auto, (max-width: 428px) 100vw, 428px\" \/><\/a><\/p>\n<p>Per la verit\u00e1 miero svegliata un po\u00b4 preoccupata perche\u00b4 la notte precedente avevo vomitato ed ero passata in 20 minuti da 100 a 20 di glicemia.. anche se mi ero recuparata rapidamente, non sapevo il giorno dopo come mi sarei sentita. Vedere tante persone belle mi ha dato forza e animo per accompagnarle in questo giorno.<\/p>\n<p>Un altro momento molto speciale e\u00b4stato quando voi guerrier@ vi siete riuniti in Via Alamos e io sono scesa nel <a href=\"https:\/\/ninalaguerrera.org\/2018\/07\/20\/el-ninamovil\/\">&#8220;Ninamovil&#8221;<\/a> a salutarvi. Mi e\u00b4 venuta la pelle d\u00b4oca quando sono arrivata nel vedervi assieme animandomi, applaudendo, sorridendo e qualcuno anche piangendo.. abbracciandomi con l\u00b4anima e io orgogliosa della vostra partecipazione ad un giorno cosi speciale con piu\u00b4di mille esseri umani di cuore.<\/p>\n<p><a href=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0247.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1196 aligncenter\" src=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0247-1024x683.jpg\" alt=\"\" width=\"423\" height=\"282\" srcset=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0247-1024x683.jpg 1024w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0247-300x200.jpg 300w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0247-768x512.jpg 768w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0247-1500x1000.jpg 1500w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0247.jpg 1732w\" sizes=\"auto, (max-width: 423px) 100vw, 423px\" \/><\/a><\/p>\n<p>La maglietta con la scritta \u201cGracias Guerrer@s\u201d che indossavo non era abbastanza.. per di piu\u00b4 sono rimasta impressionata.. E\u00b4vero che avevamo gi\u00e1\u00b4combattuto varie battaglie nei mesi precedenti con diversi Guerrier@ In Azione in posti diversi e l\u00b4appoggio di centinaia di voi attraverso la web, pero\u00b4 era la prima volta che vedevo il mio esercito di fronte.<\/p>\n<p><a href=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/Nina-camiseta-gracias-guerreros.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1204 aligncenter\" src=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/Nina-camiseta-gracias-guerreros.jpg\" alt=\"\" width=\"244\" height=\"426\" srcset=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/Nina-camiseta-gracias-guerreros.jpg 353w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/Nina-camiseta-gracias-guerreros-172x300.jpg 172w\" sizes=\"auto, (max-width: 244px) 100vw, 244px\" \/><\/a><\/p>\n<p>Ho l\u00e1bitudine di \u201cscanalizzare\u201d alle persone che vedo per la prima volta, prima di lasciarmi andare, resto assorta fissando senza dire nulla per 2-3 minuti e poi gia\u00b4 non resisto e parto con il mio \u201cHola\u201d, sorrido e se c\u00b4e\u00b4 tempo riempiamo il tempo assieme! Questo giorno mi e\u00b4\u00b4 staot difficile scanalizzarvi tutti assieme.. e non ce n\u00b4e\u00b4 stato bisogno perche\u00b4 il sentimento bello e profondo e la connessione diretta che ho sentito sono qualcosa che non mi dimentichero\u2019 mai guerrier@!<\/p>\n<p>E come se fosse poco, non solo avete camminato e corso a nome mio ma mi avete anche cantato Buon Compleanno (con 4 giorni di anticipo)! E\u00b4 stato un momento molto emotivo in cui e\u00b4 importato poco che mio padre e mia madre stonassero \ud83d\ude09 \u2013 Ah! Tra l\u00b4altro.. il 7 di ottobre coincide con il compleanno del mio papa\u00b4 e io se avessi potuto, gli avrei cantato Buon Compleanno perch\u00e9 e\u00b4 il mio guerriero alcalaino numero 1!<\/p>\n<p>Dal palco potevo vedere la postazione di massaggi e agopuntura chinese, la zona in cui i guerrier@ avevano fatto Yoga dopo la battaglia, il posto dove i G\u00f3ngora avevano distribuito frutta coloratissima e dove i fotografi e i mezzi di comunicazione presenti immortalarono questa giornata tanto speciale. Le foto e reportage sono belli ed abbiamo pure un video girato da un dron.. che fortuna avere al seguito tanti guerrier@ cosi\u00b4 versatili!<\/p>\n<div style=\"width: 820px;\" class=\"wp-video\"><!--[if lt IE 9]><script>document.createElement('video');<\/script><![endif]-->\n<video class=\"wp-video-shortcode\" id=\"video-1231-1\" width=\"820\" height=\"461\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/Nina_La_Guerrera_LOW.mp4?_=1\" \/><a href=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/Nina_La_Guerrera_LOW.mp4\">https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/Nina_La_Guerrera_LOW.mp4<\/a><\/video><\/div>\n<p><a href=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0137.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1205 aligncenter\" src=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0137-1024x683.jpg\" alt=\"\" width=\"453\" height=\"302\" srcset=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0137-1024x683.jpg 1024w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0137-300x200.jpg 300w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0137-768x512.jpg 768w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0137-1500x1000.jpg 1500w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0137.jpg 1732w\" sizes=\"auto, (max-width: 453px) 100vw, 453px\" \/><\/a> <a href=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0168.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1206 aligncenter\" src=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0168-1024x683.jpg\" alt=\"\" width=\"453\" height=\"302\" srcset=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0168-1024x683.jpg 1024w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0168-300x200.jpg 300w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0168-768x512.jpg 768w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0168-1500x1000.jpg 1500w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0168.jpg 1732w\" sizes=\"auto, (max-width: 453px) 100vw, 453px\" \/><\/a> <a href=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0159.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1202 aligncenter\" src=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0159-1024x683.jpg\" alt=\"\" width=\"445\" height=\"297\" srcset=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0159-1024x683.jpg 1024w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0159-300x200.jpg 300w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0159-768x512.jpg 768w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0159-1500x1000.jpg 1500w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0159.jpg 1732w\" sizes=\"auto, (max-width: 445px) 100vw, 445px\" \/><\/a><\/p>\n<p>Inoltre, potevo vedere la postazione delle <strong>\u201cAceituNinas\u201d<\/strong> (Aceitunas=Olive) che si sono vendute come il pane..<\/p>\n<p><a href=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0099.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1201 aligncenter\" src=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0099-1024x683.jpg\" alt=\"\" width=\"421\" height=\"281\" srcset=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0099-1024x683.jpg 1024w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0099-300x200.jpg 300w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0099-768x512.jpg 768w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0099-1500x1000.jpg 1500w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0099.jpg 1732w\" sizes=\"auto, (max-width: 421px) 100vw, 421px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0101.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-1195 aligncenter\" src=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0101-1024x683.jpg\" alt=\"\" width=\"428\" height=\"285\" srcset=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0101-1024x683.jpg 1024w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0101-300x200.jpg 300w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0101-768x512.jpg 768w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0101-1500x1000.jpg 1500w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/DSC_0101.jpg 1732w\" sizes=\"auto, (max-width: 428px) 100vw, 428px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Al nostro lato stava il <em>photocall<\/em> dove potevo vedere la mia immagine e gli <strong>organizzatori, collaboratori e patrocinatori<\/strong> che hanno appoggiato e realizzato il sogno di questa giornata:<\/p>\n<p><a href=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/Photocall-Nina.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1207 aligncenter\" src=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/Photocall-Nina-1024x622.jpg\" alt=\"\" width=\"1197\" height=\"727\" srcset=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/Photocall-Nina-1024x622.jpg 1024w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/Photocall-Nina-300x182.jpg 300w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/Photocall-Nina-768x467.jpg 768w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/Photocall-Nina-1500x912.jpg 1500w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/Photocall-Nina.jpg 1772w\" sizes=\"auto, (max-width: 1197px) 100vw, 1197px\" \/><\/a><\/p>\n<p>Moltissime grazie a tutti! Grazue a loro, i costi dell\u00b4evento sono stati molto minori dello sperato, le entrate (che vanno alla ricerca interamente) molto piu\u00b4 alte e il risultato della nostrsa missione un successo. Oltre a cio\u00b4, e\u00b4 stato realizzato un sorteggio per i partecipanti con sorprese&#8230; Spero vi sia toccato qualcosa! \ud83d\ude09<\/p>\n<p>Mi piacerebbe anche ringraziare in maniera speciale Evangelina (futura mamma, sicuramente meravigliosa.. coraggio che sei quasi alla retta finale!), Mota e Adolfo che hanno capitanato la battaglia dall\u00b4inizio alla fine dedicando un sacco di tempo e sforzi per assicurare la vittoria J. Grazie tante anche ai volontari che hanno reso possibile questa giornata.<\/p>\n<p><a href=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/carrera-todos-juntos-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1222 aligncenter\" src=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/carrera-todos-juntos-2.jpg\" alt=\"\" width=\"391\" height=\"116\" srcset=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/carrera-todos-juntos-2.jpg 391w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/carrera-todos-juntos-2-300x89.jpg 300w\" sizes=\"auto, (max-width: 391px) 100vw, 391px\" \/><\/a><\/p>\n<p>L\u00b4 incredibile risposta dei guerrier@ di Alcal\u00e1 la Real e di altri venuti da fuori, hanno superato il limite di iscrizioni (che era di 700) e di \u201cPettorine 0 solidali\u201d oltre alla menzionata generosita\u00b4 degli sponsor, degli organizzatori, collaboratori e del municipio.. si sono ricavati circa 12,000 euro per la causa di Nina e dei suoi Guerrieri In Azione. Siete grandi guerrier@.<\/p>\n<p>Spero che abbiate passato una bella giornata come l\u00b4ho passato io e che siate pronti per ripeterla il prossimo anno, la II Carrera y Senderismo solidarios &#8220;Nina la Guerrera&#8221; \ud83d\ude42<\/p>\n<p>Pensando al prossimo anno, mi chiedo se il mio controllo metabolico sara\u00b4 piu\u00b4 stabile, se potro\u00b4 fare pause piu\u00b4 lunghe tra pasti, se tollerero\u00b4 l\u00b4amido di mais, se potro\u00b4 togliermi la sonda nasogastrica o avro\u00b4 il bottone gastrico o se saro\u00b4 fuori dall\u00b4ospedale permanentemente.. Cio\u00b4 che si\u00b4 mi e\u00b4 chiaro e\u00b4 che la voglia di raggiungere tutti questi obbiettivi non manca e l\u00b4appoggio dei guerrier@ nemmeno quindi assieme sono sicura che realizzeremo molti di essi! Inoltre, il prossimo anno, succeda quel che succeda, gia\u00b4 saremo di un anno piu\u00b4 vicino alla terapia gen\u00e9tica il cui sviluppo e\u00b4 possibile grazie alle vostre contribuzioni. Lo festeggieremo a dovere con una nuova battaglia!<\/p>\n<p>Vi voglio bene guerrier@! Mille NinAbbracci<\/p>\n<p><a href=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/MG_8592_1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1211 aligncenter\" src=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/MG_8592_1-1024x683.jpg\" alt=\"\" width=\"541\" height=\"361\" srcset=\"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/MG_8592_1-1024x683.jpg 1024w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/MG_8592_1-300x200.jpg 300w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/MG_8592_1-768x512.jpg 768w, https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/MG_8592_1-1500x1000.jpg 1500w\" sizes=\"auto, (max-width: 541px) 100vw, 541px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ciao Guerrier@! Che primo compleanno con i fiocchi ho trascorso, ho festeggiato una settimana intera! La glicogenosis ci limita pero non ci ferma! Iniziamo dal 7 di octubre de 2018, una data che passera\u00b4 alla storia come la giornata in cui Nina e i suoi Guerrier@ hanno vinto la I battaglia a favore delle ricerca [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1193,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[5],"tags":[],"class_list":["post-1231","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-categorizzato"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/ninalaguerrera.org\/wp-content\/uploads\/2018\/10\/carrera-todos-juntos.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pa1s8Y-jR","_links":{"self":[{"href":"https:\/\/ninalaguerrera.org\/it\/wp-json\/wp\/v2\/posts\/1231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ninalaguerrera.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ninalaguerrera.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ninalaguerrera.org\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ninalaguerrera.org\/it\/wp-json\/wp\/v2\/comments?post=1231"}],"version-history":[{"count":4,"href":"https:\/\/ninalaguerrera.org\/it\/wp-json\/wp\/v2\/posts\/1231\/revisions"}],"predecessor-version":[{"id":1250,"href":"https:\/\/ninalaguerrera.org\/it\/wp-json\/wp\/v2\/posts\/1231\/revisions\/1250"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ninalaguerrera.org\/it\/wp-json\/wp\/v2\/media\/1193"}],"wp:attachment":[{"href":"https:\/\/ninalaguerrera.org\/it\/wp-json\/wp\/v2\/media?parent=1231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ninalaguerrera.org\/it\/wp-json\/wp\/v2\/categories?post=1231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ninalaguerrera.org\/it\/wp-json\/wp\/v2\/tags?post=1231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}